{"id":9873,"date":"2020-10-08T08:00:52","date_gmt":"2020-10-08T08:00:52","guid":{"rendered":"https:\/\/aica.com\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/"},"modified":"2025-04-02T13:18:42","modified_gmt":"2025-04-02T13:18:42","slug":"por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador","status":"publish","type":"post","link":"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/","title":{"rendered":"Por qu\u00e9 debes acudir a un quiropr\u00e1ctico si tienes un trabajo agotador"},"content":{"rendered":"<p>\u00bfTu trabajo te obliga a estar de pie todo el d\u00eda o requiere un esfuerzo f\u00edsico importante? \u00bfLlegas a casa despu\u00e9s de un estresante d\u00eda de trabajo y te encuentras buscando una bolsa de hielo? Todas estas experiencias en tu trabajo pueden suponer un esfuerzo y una tensi\u00f3n importantes para todo tu cuerpo. Los trabajos con exigencias extenuantes pueden causar un desgaste adicional en el cuerpo y eso puede dar lugar a problemas comunes como <a href=\"https:\/\/aica.com\/we-treat\/pain\/neck\/\">el dolor de espalda y de cuello<\/a>. Es importante recibir una atenci\u00f3n y un apoyo integrales con tu equipo m\u00e9dico, que incluya un <a href=\"https:\/\/www.aicaorthopedics.com\/services\/specialties\/orthopedic-spine-joint\/\">cirujano ortop\u00e9dico<\/a> y un quiropr\u00e1ctico, para ayudar a soportar y tratar tu dolor.    <\/p>\n<h2>C\u00f3mo tu trabajo puede provocar dolor de espalda<\/h2>\n<p>Quiz\u00e1 te preguntes c\u00f3mo puede afectarte m\u00e1s negativamente la actividad f\u00edsica que realizas en tu trabajo que el resto de tus actividades diarias. En general, esto se debe a que las actividades f\u00edsicas que se realizan en el trabajo suelen ser m\u00e1s exigentes f\u00edsicamente y repetitivas, con menos oportunidades de descansar el cuerpo y, adem\u00e1s, se realizan durante periodos de tiempo m\u00e1s largos. Salir a correr el fin de semana o levantar pesas en el gimnasio local son actividades que buscas para mantenerte en forma, ponerte en forma y hacer ejercicio. El esfuerzo f\u00edsico relacionado con el trabajo tiene menos que ver con el ejercicio y m\u00e1s con movimientos repetitivos que pueden empezar a pasar factura a tu cuerpo.   <\/p>\n<p>Los trabajos que te obligan a estar de pie todo el d\u00eda con pocas oportunidades de descanso, o los trabajos que requieren levantar objetos pesados o permanecer en posturas encorvadas durante largos periodos de tiempo, pueden empezar a estresar todo tu cuerpo, desde el cuello y la columna vertebral hasta las rodillas y los pies. Puedes empezar a desarrollar <a href=\"https:\/\/aica.com\/we-treat\/pain\/shoulder\/\">dolor cr\u00f3nico en los hombros<\/a> o dolor en el cuello y en la parte superior de la espalda por una mala postura. Puedes experimentar molestias y dolores importantes en la parte baja de la espalda y las piernas por todo lo que levantas durante horas. El estr\u00e9s y la tensi\u00f3n de tu cuerpo tambi\u00e9n pueden hacerte m\u00e1s susceptible a las lesiones.   <\/p>\n<h2>Quiropr\u00e1cticos y estr\u00e9s laboral<\/h2>\n<p>Cuando se trata de tratar un cuerpo sobrecargado y estresado, los quiropr\u00e1cticos ofrecen una opci\u00f3n de tratamiento natural y no invasivo para ayudar a abordar el dolor y las molestias, al tiempo que fortalecen el cuerpo. Los quiropr\u00e1cticos tratan diversos problemas centr\u00e1ndose en la columna vertebral y el sistema nervioso. El sistema nervioso empieza en tu cerebro y se apoya y aloja en la columna vertebral. Los nervios del cuerpo ayudan a comunicar mensajes del cerebro sobre cada peque\u00f1a cosa que haces, desde caminar hasta digerir las comidas o experimentar dolor. Cuando tu columna vertebral est\u00e1 comprometida debido a un desgaste importante, esto puede provocar problemas neurol\u00f3gicos y s\u00edntomas de dolor, y puede llevarte a necesitar los cuidados de un cirujano ortop\u00e9dico.    <\/p>\n<p>La columna vertebral es lo que ayuda a sostener todo tu cuerpo y est\u00e1 hecha para soportar tu peso y sostenerte a trav\u00e9s de una variedad de movimientos. Sin embargo, cuando el esfuerzo f\u00edsico de tu trabajo empieza a desgastar tu columna y a afectar a tu postura o a los m\u00fasculos que la rodean y la sostienen, puedes empezar a desarrollar dolor e incluso lesiones. Los quiropr\u00e1cticos estudian y tratan la columna vertebral por su impacto en el resto de tu cuerpo y ayudan a desarrollar planes de tratamiento para tratar el dolor, as\u00ed como para fortalecer y proteger tu cuerpo de futuros dolores y lesiones.  <\/p>\n<h2>Tratamientos Quiropr\u00e1cticos para el Dolor Laboral<\/h2>\n<p>La atenci\u00f3n quiropr\u00e1ctica para el dolor y las lesiones relacionados con el trabajo es una forma suave y de bajo riesgo de abordar el dolor de cuello y espalda. Los quiropr\u00e1cticos no recetan medicamentos ni utilizan procedimientos invasivos como los cirujanos ortop\u00e9dicos; en lugar de ello, se centran en identificar las zonas en las que la columna est\u00e1 desalineada y trabajan para devolver a la columna su posici\u00f3n correcta. Cuando tu cuerpo experimenta una postura adecuada, los m\u00fasculos y tejidos circundantes de la columna vertebral no tienen que esforzarse tanto para sostener el resto del cuerpo.  <\/p>\n<p>El dolor de espalda es una de las razones m\u00e1s frecuentes por las que la gente busca atenci\u00f3n m\u00e9dica. Los quiropr\u00e1cticos son expertos en identificar desajustes en la columna vertebral y tratar diversos <a href=\"https:\/\/aica.com\/we-treat\/pain\/back-pain\/\">dolores de<\/a> cuello y espalda. Cuando visites a un quiropr\u00e1ctico, es probable que realice una serie de suaves t\u00e9cnicas de ajuste en la columna vertebral para ayudar a restablecer la postura correcta y tambi\u00e9n a reducir cualquier presi\u00f3n indebida sobre los nervios. Los quiropr\u00e1cticos tambi\u00e9n practican un enfoque m\u00e1s hol\u00edstico del tratamiento, en el sentido de que tambi\u00e9n ayudar\u00e1n a proporcionar tratamiento y t\u00e9cnicas sobre c\u00f3mo mejorar tu postura y fortalecer tu columna vertebral para que resista mejor el desgaste diario.   <\/p>\n<h3>Atenci\u00f3n quiropr\u00e1ctica preventiva<\/h3>\n<p>Independientemente del tipo de trabajo que tengas, es probable que experimentes alg\u00fan tipo de dolor de espalda en un momento u otro. La atenci\u00f3n quiropr\u00e1ctica es una forma estupenda de tratar el dolor una vez que lo experimentas, pero tambi\u00e9n es estupenda para la atenci\u00f3n preventiva. Por ejemplo, la atenci\u00f3n quiropr\u00e1ctica es un gran recurso para el cuidado continuado mientras trabajas en un empleo extenuante con graves exigencias f\u00edsicas, porque puede ayudar a tratar, apoyar y mantener tu columna vertebral. En AICA Ortopedia, nuestro equipo de profesionales m\u00e9dicos de m\u00faltiples especialidades te ofrece el apoyo que necesitas para mantener tu cuerpo seguro y fuerte mientras est\u00e1s en casa y en el trabajo. <a href=\"tel:(404)%20855-2141\">Llama<\/a> hoy mismo para concertar una cita con un quiropr\u00e1ctico o un cirujano ortop\u00e9dico.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfTu trabajo te obliga a estar de pie todo el d\u00eda o requiere un esfuerzo f\u00edsico importante? \u00bfLlegas a casa despu\u00e9s de un estresante d\u00eda de trabajo y te encuentras&#8230;<\/p>\n","protected":false},"author":9,"featured_media":7626,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[198],"tags":[254,234],"class_list":["post-9873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quiropractico","tag-dolor-de-espalda","tag-quiropracticos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Por qu\u00e9 deber\u00edas acudir a un quiropr\u00e1ctico si tienes un trabajo agotador<\/title>\n<meta name=\"description\" content=\"\u00bfTienes un trabajo agotador? Es muy importante que cuides tu espalda acudiendo a un quiropr\u00e1ctico. Descubre c\u00f3mo pueden ayudarte nuestros m\u00e9dicos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 deber\u00edas acudir a un quiropr\u00e1ctico si tienes un trabajo agotador\" \/>\n<meta property=\"og:description\" content=\"\u00bfTienes un trabajo agotador? Es muy importante que cuides tu espalda acudiendo a un quiropr\u00e1ctico. Descubre c\u00f3mo pueden ayudarte nuestros m\u00e9dicos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/\" \/>\n<meta property=\"og:site_name\" content=\"AICA Orthopedics\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-08T08:00:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-02T13:18:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/Why-You-Should-See-A-Chiropractor-If-You-Have-A-Strenuous-Job.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aicaos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"aicaos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\\\/\"},\"author\":{\"name\":\"aicaos\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#\\\/schema\\\/person\\\/d68d1233a139d55e37d8e4d867f6dc24\"},\"headline\":\"Por qu\u00e9 debes acudir a un quiropr\u00e1ctico si tienes un trabajo agotador\",\"datePublished\":\"2020-10-08T08:00:52+00:00\",\"dateModified\":\"2025-04-02T13:18:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\\\/\"},\"wordCount\":1027,\"image\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aica.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Why-You-Should-See-A-Chiropractor-If-You-Have-A-Strenuous-Job.jpg\",\"keywords\":[\"dolor de espalda\",\"quiropr\u00e1cticos\"],\"articleSection\":[\"Quiropr\u00e1ctico\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\\\/\",\"url\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\\\/\",\"name\":\"Por qu\u00e9 deber\u00edas acudir a un quiropr\u00e1ctico si tienes un trabajo agotador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aica.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Why-You-Should-See-A-Chiropractor-If-You-Have-A-Strenuous-Job.jpg\",\"datePublished\":\"2020-10-08T08:00:52+00:00\",\"dateModified\":\"2025-04-02T13:18:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#\\\/schema\\\/person\\\/d68d1233a139d55e37d8e4d867f6dc24\"},\"description\":\"\u00bfTienes un trabajo agotador? Es muy importante que cuides tu espalda acudiendo a un quiropr\u00e1ctico. Descubre c\u00f3mo pueden ayudarte nuestros m\u00e9dicos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aica.com\\\/es\\\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aica.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Why-You-Should-See-A-Chiropractor-If-You-Have-A-Strenuous-Job.jpg\",\"contentUrl\":\"https:\\\/\\\/aica.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Why-You-Should-See-A-Chiropractor-If-You-Have-A-Strenuous-Job.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/aica.com\\\/es\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por qu\u00e9 debes acudir a un quiropr\u00e1ctico si tienes un trabajo agotador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/aica.com\\\/es\\\/\",\"name\":\"AICA Orthopedics\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aica.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#\\\/schema\\\/person\\\/d68d1233a139d55e37d8e4d867f6dc24\",\"name\":\"aicaos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g\",\"caption\":\"aicaos\"},\"url\":\"https:\\\/\\\/aica.com\\\/es\\\/author\\\/aicaos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 deber\u00edas acudir a un quiropr\u00e1ctico si tienes un trabajo agotador","description":"\u00bfTienes un trabajo agotador? Es muy importante que cuides tu espalda acudiendo a un quiropr\u00e1ctico. Descubre c\u00f3mo pueden ayudarte nuestros m\u00e9dicos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 deber\u00edas acudir a un quiropr\u00e1ctico si tienes un trabajo agotador","og_description":"\u00bfTienes un trabajo agotador? Es muy importante que cuides tu espalda acudiendo a un quiropr\u00e1ctico. Descubre c\u00f3mo pueden ayudarte nuestros m\u00e9dicos.","og_url":"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/","og_site_name":"AICA Orthopedics","article_published_time":"2020-10-08T08:00:52+00:00","article_modified_time":"2025-04-02T13:18:42+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/Why-You-Should-See-A-Chiropractor-If-You-Have-A-Strenuous-Job.jpg","type":"image\/jpeg"}],"author":"aicaos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"aicaos","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/#article","isPartOf":{"@id":"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/"},"author":{"name":"aicaos","@id":"https:\/\/aica.com\/es\/#\/schema\/person\/d68d1233a139d55e37d8e4d867f6dc24"},"headline":"Por qu\u00e9 debes acudir a un quiropr\u00e1ctico si tienes un trabajo agotador","datePublished":"2020-10-08T08:00:52+00:00","dateModified":"2025-04-02T13:18:42+00:00","mainEntityOfPage":{"@id":"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/"},"wordCount":1027,"image":{"@id":"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/#primaryimage"},"thumbnailUrl":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/Why-You-Should-See-A-Chiropractor-If-You-Have-A-Strenuous-Job.jpg","keywords":["dolor de espalda","quiropr\u00e1cticos"],"articleSection":["Quiropr\u00e1ctico"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/","url":"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/","name":"Por qu\u00e9 deber\u00edas acudir a un quiropr\u00e1ctico si tienes un trabajo agotador","isPartOf":{"@id":"https:\/\/aica.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/#primaryimage"},"image":{"@id":"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/#primaryimage"},"thumbnailUrl":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/Why-You-Should-See-A-Chiropractor-If-You-Have-A-Strenuous-Job.jpg","datePublished":"2020-10-08T08:00:52+00:00","dateModified":"2025-04-02T13:18:42+00:00","author":{"@id":"https:\/\/aica.com\/es\/#\/schema\/person\/d68d1233a139d55e37d8e4d867f6dc24"},"description":"\u00bfTienes un trabajo agotador? Es muy importante que cuides tu espalda acudiendo a un quiropr\u00e1ctico. Descubre c\u00f3mo pueden ayudarte nuestros m\u00e9dicos.","breadcrumb":{"@id":"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/#primaryimage","url":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/Why-You-Should-See-A-Chiropractor-If-You-Have-A-Strenuous-Job.jpg","contentUrl":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/Why-You-Should-See-A-Chiropractor-If-You-Have-A-Strenuous-Job.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/aica.com\/es\/por-que-debes-acudir-a-un-quiropractico-si-tienes-un-trabajo-agotador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/aica.com\/es\/homepage\/"},{"@type":"ListItem","position":2,"name":"Por qu\u00e9 debes acudir a un quiropr\u00e1ctico si tienes un trabajo agotador"}]},{"@type":"WebSite","@id":"https:\/\/aica.com\/es\/#website","url":"https:\/\/aica.com\/es\/","name":"AICA Orthopedics","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aica.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/aica.com\/es\/#\/schema\/person\/d68d1233a139d55e37d8e4d867f6dc24","name":"aicaos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g","caption":"aicaos"},"url":"https:\/\/aica.com\/es\/author\/aicaos\/"}]}},"_links":{"self":[{"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/posts\/9873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/comments?post=9873"}],"version-history":[{"count":0,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/posts\/9873\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/media\/7626"}],"wp:attachment":[{"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/media?parent=9873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/categories?post=9873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/tags?post=9873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}