{"id":10249,"date":"2019-07-24T08:00:50","date_gmt":"2019-07-24T08:00:50","guid":{"rendered":"https:\/\/aica.com\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/"},"modified":"2025-04-02T13:39:05","modified_gmt":"2025-04-02T13:39:05","slug":"por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos","status":"publish","type":"post","link":"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/","title":{"rendered":"Por qu\u00e9 se asocian neurocirujanos y cirujanos ortop\u00e9dicos"},"content":{"rendered":"<p>&#8220;Si necesito que me eval\u00faen por un problema de columna, o si necesito <a href=\"https:\/\/aica.com\/we-treat\/pain\/spine\/spinal-cord-surgery\/\">cirug\u00eda de columna<\/a>, \u00bfdebo acudir a un <a href=\"https:\/\/aica.com\/es\/neurosurgeons\/\"><strong>neurocirujano<\/strong> <\/a>o a un traumat\u00f3logo?&#8221;<\/p>\n<p>En el mundo actual de la medicina, la cirug\u00eda de la columna vertebral est\u00e1 incorporando ambas especialidades, ya que ambos grupos de m\u00e9dicos comprenden la importancia del oficio del otro.<br \/>\n<!--more--><br \/>\nEn el mundo de la medicina, no hay especialistas en columna vertebral fijos en cuanto a titulaci\u00f3n, por lo que esto puede ser preocupante y confuso para algunos pacientes.<\/p>\n<p>Un neurocirujano es alguien certificado por la Junta Americana de Cirug\u00eda Neurol\u00f3gica, y un <a href=\"https:\/\/aica.com\/common-questions-for-orthopedic-surgeons\/\"><strong>cirujano ortop\u00e9dico<\/strong><\/a> recibe su certificaci\u00f3n de la Junta Americana de Cirug\u00eda Ortop\u00e9dica. En el futuro, bien podr\u00eda haber un especialista en columna vertebral, pero por ahora, las dos especialidades seguir\u00e1n trabajando juntas para ofrecer a los pacientes su nivel combinado de conocimientos. <\/p>\n<h2>Formaci\u00f3n de neurocirujanos<\/h2>\n<p>Los neurocirujanos de todo el pa\u00eds reciben una formaci\u00f3n rigurosa en todos los aspectos de las pr\u00e1cticas quir\u00fargicas y no quir\u00fargicas relacionadas con el tratamiento de la columna vertebral. Tras completar un programa m\u00e9dico acreditado, pasan a un programa de residencia de seis o siete a\u00f1os en el que adquieren experiencia pr\u00e1ctica en cientos de procedimientos de la columna vertebral. Aunque se cree que los neurocirujanos son cirujanos cerebrales, muchos de los procedimientos que realizan est\u00e1n relacionados con la columna vertebral.  <\/p>\n<h3>Formaci\u00f3n de Cirujano Ortop\u00e9dico<\/h3>\n<p>Al igual que los neurocirujanos, los cirujanos ortop\u00e9dicos deben soportar un alto nivel de formaci\u00f3n y pasar por un programa de residencia de cuatro a cinco a\u00f1os tras su formaci\u00f3n en la facultad de medicina. En su programa de residencia, est\u00e1n expuestos a una amplia variedad de cirug\u00edas de columna vertebral, con gran \u00e9nfasis tambi\u00e9n en traumatismos y operaciones articulares. Esta especialidad, al igual que la neurocirug\u00eda, tiene la opci\u00f3n de especializarse tambi\u00e9n en la columna vertebral para adquirir m\u00e1s conocimientos y aumentar su conjunto de habilidades.  <\/p>\n<h3>Ambas disciplinas pueden especializarse en cirug\u00eda de la columna vertebral<\/h3>\n<p>A lo largo de los a\u00f1os, tanto los neurocirujanos como los cirujanos ortop\u00e9dicos han ampliado su formaci\u00f3n en lo que respecta a la columna vertebral para poder tratar mejor a sus pacientes. Ambos pueden denominarse especialistas en columna vertebral, ya que pueden tratar afecciones como hernias discales y enfermedades degenerativas del disco, estenosis espinal y escoliosis. <\/p>\n<h3>Diferencias<\/h3>\n<p>Aunque los neurocirujanos y los cirujanos ortop\u00e9dicos tienen mucho en com\u00fan en cuanto a sus conocimientos sobre la columna vertebral, hay algunas cosas que los diferencian. Los neurocirujanos se especializan en una zona llamada duramadre, que se encuentra en el revestimiento del canal raqu\u00eddeo. <\/p>\n<p>As\u00ed, los tumores de m\u00e9dula espinal, los quistes aracnoideos, la siringomielia, la malformaci\u00f3n de Chiari, la malformaci\u00f3n arteriovenosa de la m\u00e9dula espinal, la diplomielia o diastematomielia, la m\u00e9dula espinal anclada, la espina b\u00edfida o mielomeningocele, el lipomielomeningocele, los tumores en la uni\u00f3n de la base del cr\u00e1neo y la columna cervical superior, los tumores de las ra\u00edces nerviosas y algunos otros diagn\u00f3sticos siguen siendo competencia del neurocirujano.<\/p>\n<h3>Compartir los mismos intereses<\/h3>\n<p>Con tantos avances m\u00e9dicos y el af\u00e1n de aprender m\u00e1s en ambos extremos de las especialidades, en los \u00faltimos a\u00f1os tanto los neurocirujanos como los cirujanos ortop\u00e9dicos han dejado a un lado las diferencias y la competencia y se han dado cuenta de que aunando fuerzas y habilidades podr\u00edan ayudar a muchos m\u00e1s pacientes.<\/p>\n<p>Muchas organizaciones cient\u00edficas internacionales abren ahora sus puertas a m\u00e9dicos de ambas especialidades, como la North American Spine Society, la Scoliosis Research Society, la Cervical Spine Research Society y otras. Esta amistad y asociaci\u00f3n profesional de cirujanos ortop\u00e9dicos y neurocirujanos ser\u00e1 muy beneficiosa para los pacientes. <\/p>\n<h3>Habla, haz preguntas<\/h3>\n<p>Enterarte de que puedes necesitar cirug\u00eda de columna ya puede ser inquietante de por s\u00ed, pero lo que puede ser a\u00fan m\u00e1s perturbador es enterarte de que tu cirujano ortop\u00e9dico est\u00e1 m\u00e1s especializado en el cuidado de las articulaciones que en la cirug\u00eda de columna, o que tu neurocirujano se centra m\u00e1s en zonas del cerebro y tiene menos conocimientos sobre la columna vertebral.<\/p>\n<p>Como paciente en la sociedad actual, utiliza tu capacidad para acceder a la investigaci\u00f3n y aprender sobre los m\u00e9dicos que trabajan contigo y, si no puedes hacerlo, haz las preguntas dif\u00edciles. Pregunta a tu cirujano sobre su formaci\u00f3n y su especialidad y aseg\u00farate de que te ha expuesto todas las opciones. <\/p>\n<p>Nuestro equipo en AICA Orthopedics se ha especializado <a href=\"https:\/\/aica.com\/we-treat\/pain\/spine\/\"><strong>m\u00e9dicos de columna de Atlanta<\/strong><\/a> que pueden ayudar a tratar una variedad de afecciones y m\u00e9dicos que siguen desarrollando sus habilidades mediante una educaci\u00f3n y formaci\u00f3n continuas. Llama hoy al <a href=\"tel:4048552141\">(404) 855-2141<\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Si necesito que me eval\u00faen por un problema de columna, o si necesito cirug\u00eda de columna, \u00bfdebo acudir a un neurocirujano o a un traumat\u00f3logo?&#8221; En el mundo actual de&#8230;<\/p>\n","protected":false},"author":9,"featured_media":7280,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[243],"tags":[],"class_list":["post-10249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cuidado-de-la-columna-vertebral"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Por qu\u00e9 se asocian neurocirujanos y cirujanos ortop\u00e9dicos | AICA Orthopedics<\/title>\n<meta name=\"description\" content=\"Visita nuestro blog para saber por qu\u00e9 los neurocirujanos y los cirujanos ortop\u00e9dicos forman equipo. Comprueba por qu\u00e9 AICA es la cl\u00ednica ortop\u00e9dica l\u00edder de Atlanta, \u00a1llama hoy mismo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 se asocian neurocirujanos y cirujanos ortop\u00e9dicos | AICA Orthopedics\" \/>\n<meta property=\"og:description\" content=\"Visita nuestro blog para saber por qu\u00e9 los neurocirujanos y los cirujanos ortop\u00e9dicos forman equipo. Comprueba por qu\u00e9 AICA es la cl\u00ednica ortop\u00e9dica l\u00edder de Atlanta, \u00a1llama hoy mismo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/\" \/>\n<meta property=\"og:site_name\" content=\"AICA Orthopedics\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-24T08:00:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-02T13:39:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/Why-Neurosurgeons-and-Orthopedic-Surgeons-Are-Pairing-Up-AICA-Orthopedics-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aicaos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"aicaos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\\\/\"},\"author\":{\"name\":\"aicaos\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#\\\/schema\\\/person\\\/d68d1233a139d55e37d8e4d867f6dc24\"},\"headline\":\"Por qu\u00e9 se asocian neurocirujanos y cirujanos ortop\u00e9dicos\",\"datePublished\":\"2019-07-24T08:00:50+00:00\",\"dateModified\":\"2025-04-02T13:39:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\\\/\"},\"wordCount\":844,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aica.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Why-Neurosurgeons-and-Orthopedic-Surgeons-Are-Pairing-Up-AICA-Orthopedics-scaled-1.jpg\",\"articleSection\":[\"Cuidado de la columna vertebral\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\\\/\",\"url\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\\\/\",\"name\":\"Por qu\u00e9 se asocian neurocirujanos y cirujanos ortop\u00e9dicos | AICA Orthopedics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aica.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Why-Neurosurgeons-and-Orthopedic-Surgeons-Are-Pairing-Up-AICA-Orthopedics-scaled-1.jpg\",\"datePublished\":\"2019-07-24T08:00:50+00:00\",\"dateModified\":\"2025-04-02T13:39:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#\\\/schema\\\/person\\\/d68d1233a139d55e37d8e4d867f6dc24\"},\"description\":\"Visita nuestro blog para saber por qu\u00e9 los neurocirujanos y los cirujanos ortop\u00e9dicos forman equipo. Comprueba por qu\u00e9 AICA es la cl\u00ednica ortop\u00e9dica l\u00edder de Atlanta, \u00a1llama hoy mismo!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aica.com\\\/es\\\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aica.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Why-Neurosurgeons-and-Orthopedic-Surgeons-Are-Pairing-Up-AICA-Orthopedics-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/aica.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Why-Neurosurgeons-and-Orthopedic-Surgeons-Are-Pairing-Up-AICA-Orthopedics-scaled-1.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/aica.com\\\/es\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por qu\u00e9 se asocian neurocirujanos y cirujanos ortop\u00e9dicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/aica.com\\\/es\\\/\",\"name\":\"AICA Orthopedics\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aica.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#\\\/schema\\\/person\\\/d68d1233a139d55e37d8e4d867f6dc24\",\"name\":\"aicaos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g\",\"caption\":\"aicaos\"},\"url\":\"https:\\\/\\\/aica.com\\\/es\\\/author\\\/aicaos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 se asocian neurocirujanos y cirujanos ortop\u00e9dicos | AICA Orthopedics","description":"Visita nuestro blog para saber por qu\u00e9 los neurocirujanos y los cirujanos ortop\u00e9dicos forman equipo. Comprueba por qu\u00e9 AICA es la cl\u00ednica ortop\u00e9dica l\u00edder de Atlanta, \u00a1llama hoy mismo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 se asocian neurocirujanos y cirujanos ortop\u00e9dicos | AICA Orthopedics","og_description":"Visita nuestro blog para saber por qu\u00e9 los neurocirujanos y los cirujanos ortop\u00e9dicos forman equipo. Comprueba por qu\u00e9 AICA es la cl\u00ednica ortop\u00e9dica l\u00edder de Atlanta, \u00a1llama hoy mismo!","og_url":"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/","og_site_name":"AICA Orthopedics","article_published_time":"2019-07-24T08:00:50+00:00","article_modified_time":"2025-04-02T13:39:05+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/Why-Neurosurgeons-and-Orthopedic-Surgeons-Are-Pairing-Up-AICA-Orthopedics-scaled-1.jpg","type":"image\/jpeg"}],"author":"aicaos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"aicaos","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/#article","isPartOf":{"@id":"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/"},"author":{"name":"aicaos","@id":"https:\/\/aica.com\/es\/#\/schema\/person\/d68d1233a139d55e37d8e4d867f6dc24"},"headline":"Por qu\u00e9 se asocian neurocirujanos y cirujanos ortop\u00e9dicos","datePublished":"2019-07-24T08:00:50+00:00","dateModified":"2025-04-02T13:39:05+00:00","mainEntityOfPage":{"@id":"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/"},"wordCount":844,"commentCount":0,"image":{"@id":"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/#primaryimage"},"thumbnailUrl":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/Why-Neurosurgeons-and-Orthopedic-Surgeons-Are-Pairing-Up-AICA-Orthopedics-scaled-1.jpg","articleSection":["Cuidado de la columna vertebral"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/","url":"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/","name":"Por qu\u00e9 se asocian neurocirujanos y cirujanos ortop\u00e9dicos | AICA Orthopedics","isPartOf":{"@id":"https:\/\/aica.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/#primaryimage"},"image":{"@id":"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/#primaryimage"},"thumbnailUrl":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/Why-Neurosurgeons-and-Orthopedic-Surgeons-Are-Pairing-Up-AICA-Orthopedics-scaled-1.jpg","datePublished":"2019-07-24T08:00:50+00:00","dateModified":"2025-04-02T13:39:05+00:00","author":{"@id":"https:\/\/aica.com\/es\/#\/schema\/person\/d68d1233a139d55e37d8e4d867f6dc24"},"description":"Visita nuestro blog para saber por qu\u00e9 los neurocirujanos y los cirujanos ortop\u00e9dicos forman equipo. Comprueba por qu\u00e9 AICA es la cl\u00ednica ortop\u00e9dica l\u00edder de Atlanta, \u00a1llama hoy mismo!","breadcrumb":{"@id":"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/#primaryimage","url":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/Why-Neurosurgeons-and-Orthopedic-Surgeons-Are-Pairing-Up-AICA-Orthopedics-scaled-1.jpg","contentUrl":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/Why-Neurosurgeons-and-Orthopedic-Surgeons-Are-Pairing-Up-AICA-Orthopedics-scaled-1.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/aica.com\/es\/por-que-se-asocian-neurocirujanos-y-cirujanos-ortopedicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/aica.com\/es\/homepage\/"},{"@type":"ListItem","position":2,"name":"Por qu\u00e9 se asocian neurocirujanos y cirujanos ortop\u00e9dicos"}]},{"@type":"WebSite","@id":"https:\/\/aica.com\/es\/#website","url":"https:\/\/aica.com\/es\/","name":"AICA Orthopedics","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aica.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/aica.com\/es\/#\/schema\/person\/d68d1233a139d55e37d8e4d867f6dc24","name":"aicaos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g","caption":"aicaos"},"url":"https:\/\/aica.com\/es\/author\/aicaos\/"}]}},"_links":{"self":[{"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/posts\/10249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/comments?post=10249"}],"version-history":[{"count":0,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/posts\/10249\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/media\/7280"}],"wp:attachment":[{"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/media?parent=10249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/categories?post=10249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/tags?post=10249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}