{"id":10011,"date":"2020-08-14T08:00:43","date_gmt":"2020-08-14T08:00:43","guid":{"rendered":"https:\/\/aica.com\/como-aliviar-el-dolor-lumbar-al-dormir\/"},"modified":"2025-04-26T07:31:32","modified_gmt":"2025-04-26T07:31:32","slug":"como-aliviar-el-dolor-lumbar-al-dormir","status":"publish","type":"post","link":"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/","title":{"rendered":"C\u00f3mo aliviar el dolor lumbar al dormir"},"content":{"rendered":"<p>Todos sabemos lo importante que es el sue\u00f1o de calidad para nuestra salud y, por desgracia, muchos de nosotros no lo conseguimos debido a que llevamos una vida muy ajetreada y nunca tenemos tiempo suficiente al d\u00eda. Pero si adem\u00e1s a\u00f1ades que sientes dolor cada vez que intentas dormir, hay a\u00fan m\u00e1s probabilidades de que no est\u00e9s durmiendo el sue\u00f1o de calidad que tu cuerpo necesita. Tanto dormir mal como el dolor de espalda cr\u00f3nico pueden tener un impacto significativo en nuestra perspectiva diaria y en nuestro bienestar general. Un <a href=\"https:\/\/aica.com\/es\/we-treat\/dolor\/columna-vertebral\/\">m\u00e9dico especialista en columna vertebral<\/a> puede ayudarte a tratar tu dolor de espalda y tambi\u00e9n a identificar formas o aliviar el dolor de espalda para que puedas dormir mejor y experimentar una curaci\u00f3n m\u00e1s r\u00e1pida. He aqu\u00ed algunas ideas sobre c\u00f3mo aliviar el <a href=\"https:\/\/aica.com\/es\/we-treat\/dolor\/lumbalgia\/\">dolor<\/a> lumbar mientras duermes, basadas en la experiencia de los mejores m\u00e9dicos especialistas en columna vertebral de Atlanta.<\/p>\n<h2>Intenta dormir boca arriba<\/h2>\n<p>Si a\u00fan no duermes boca arriba, puede ser un buen momento para probar algo nuevo. Dormir boca arriba puede permitir que la columna vertebral est\u00e9 en su posici\u00f3n m\u00e1s natural y aliviar la presi\u00f3n de zonas concretas de las v\u00e9rtebras donde sientas dolor. Esta postura para dormir tambi\u00e9n ayuda a distribuir uniformemente el peso de tu cuerpo a lo largo de la columna vertebral, lo que tambi\u00e9n contribuye a minimizar los puntos de presi\u00f3n. Para lograr una alineaci\u00f3n saludable de la cabeza, el cuello y la columna vertebral, tambi\u00e9n puedes considerar la posibilidad de ponerte una almohada debajo de las rodillas para aliviar tambi\u00e9n la presi\u00f3n sobre las caderas, o colocar una almohada peque\u00f1a o una toalla enrollada debajo de la parte baja de la espalda.<\/p>\n<h2>Intenta dormir de lado<\/h2>\n<p>Dormir de lado puede ocupar un segundo lugar respecto a dormir boca arriba, pero es la postura preferida para dormir de muchas personas. Lo importante al dormir de lado es utilizar almohadas de apoyo. Sin ning\u00fan apoyo adicional, es posible que tu columna vertebral no pueda descansar en su alineaci\u00f3n m\u00e1s natural, lo que en realidad puede causar m\u00e1s molestias. Cuando duermas de lado, intenta colocar una almohada entre las rodillas para ayudar a abrir las caderas e imitar la postura natural de la columna. Mantener las rodillas ligeramente flexionadas e inclinadas hacia el pecho tambi\u00e9n ayuda a la columna a encontrar su posici\u00f3n neutra.<\/p>\n<h2>Evita dormir boca abajo<\/h2>\n<p>Lo sentimos, \u00a1dormidores boca abajo! En general, los m\u00e9dicos no recomiendan dormir boca abajo, ya que ejerce mucha presi\u00f3n sobre la columna vertebral y no permite que \u00e9sta descanse en su posici\u00f3n neutra. Como la mayor parte del peso del cuerpo se centraliza en el centro, esto supone una tensi\u00f3n a\u00f1adida para la columna vertebral. Cuando la columna se tensa mientras duermes, esto puede a\u00f1adirse a las molestias y el dolor que ya experimentas en la zona lumbar. Si tienes problemas para conciliar el sue\u00f1o sin estar tumbado boca abajo, intenta colocar una almohada debajo del est\u00f3mago para ayudar a elevar la parte inferior de la columna hasta una posici\u00f3n m\u00e1s neutra con la parte superior de la columna y el cuello.<\/p>\n<h2>Mejora la higiene del sue\u00f1o<\/h2>\n<p>La higiene del sue\u00f1o se refiere a las formas saludables de prepararnos para dormir. Esto incluye evitar los estimulantes antes de acostarse, como la cafe\u00edna, e intentar evitar las luces azules de las pantallas de m\u00f3viles y tabletas justo antes de dormir. Sin embargo, tambi\u00e9n hay formas de ayudar proactivamente a tu cuerpo a relajarse antes de acostarse, como el yoga y los estiramientos. Desarrollar una rutina antes de acostarse que incluya ligeros estiramientos y aumentar el flujo sangu\u00edneo por el cuerpo puede indicar a tu cerebro que es hora de relajarse. Tu m\u00e9dico especialista en columna vertebral y tu fisioterapeuta pueden recomendarte estiramientos antes de acostarte que <a href=\"https:\/\/aica.com\/es\/las-5-posturas-correctas-al-dormir-para-reducir-el-dolor-de-espalda\/\">te ayuden a reducir el dolor en la zona lumbar<\/a>.<\/p>\n<h2>Mejora la fuerza y la flexibilidad<\/h2>\n<p>El ejercicio regular y la actividad f\u00edsica son formas estupendas de mejorar y fomentar unos patrones de sue\u00f1o saludables, y tambi\u00e9n pueden ayudar a reducir el dolor lumbar. Los ejercicios espec\u00edficos pueden dirigirse a las zonas que rodean la zona lumbar para ayudar a fortalecer los m\u00fasculos y tendones que la sostienen. Unos m\u00fasculos m\u00e1s fuertes alrededor de la columna vertebral permiten al cuerpo sostenerla de forma saludable y tambi\u00e9n pueden mejorar la postura.<\/p>\n<p>Centrarse en el fortalecimiento de los m\u00fasculos de la espalda puede ayudar a reducir las molestias cuando se intenta mantener una postura correcta durante largos periodos de tiempo. Cuanta m\u00e1s fuerza tengas tanto en los m\u00fasculos de la espalda como en los abdominales, m\u00e1s capaz ser\u00e1 tu cuerpo de mantener una postura saludable. Practicar estiramientos y ejercicios que mejoren la flexibilidad en estas zonas tambi\u00e9n puede permitir al cuerpo absorber mejor cualquier giro o voltereta y mantener la espalda a salvo.<\/p>\n<p>Controlar tus h\u00e1bitos de sue\u00f1o y tu postura al dormir es una forma de contribuir a un plan de tratamiento del dolor lumbar. Habla de tus s\u00edntomas de dolor de espalda, incluyendo cu\u00e1ndo lo notas con m\u00e1s frecuencia y c\u00f3mo es el dolor, con tu m\u00e9dico de columna para que pueda proporcionarte un diagn\u00f3stico preciso y un plan de tratamiento personalizado. Los m\u00e9dicos de columna de Ortopedia AICA forman parte de un equipo de <a href=\"https:\/\/aica.com\/es\/medicos-ortopedicos\/\">m\u00e9dicos ortop\u00e9dicos<\/a>, <a href=\"https:\/\/aica.com\/es\/services\/fisioterapia\/\">fisioterapeutas<\/a> y <a href=\"https:\/\/aica.com\/es\/quiropracticos\/\">quiropr\u00e1cticos<\/a> que trabajan juntos para proporcionarte la atenci\u00f3n integral que necesitas para aliviar definitivamente tu lumbalgia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos sabemos lo importante que es el sue\u00f1o de calidad para nuestra salud y, por desgracia, muchos de nosotros no lo conseguimos debido a que llevamos una vida muy ajetreada&#8230;<\/p>\n","protected":false},"author":9,"featured_media":7588,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[192],"tags":[210],"class_list":["post-10011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recuperacion-de-accidentes","tag-dolor-lumbar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo aliviar el dolor lumbar al dormir - AICA Orthopedics<\/title>\n<meta name=\"description\" content=\"Todos sabemos lo importante que es el sue\u00f1o de calidad para nuestra salud y, por desgracia, muchos de nosotros no lo conseguimos debido a nuestras ajetreadas vidas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo aliviar el dolor lumbar al dormir - AICA Orthopedics\" \/>\n<meta property=\"og:description\" content=\"Todos sabemos lo importante que es el sue\u00f1o de calidad para nuestra salud y, por desgracia, muchos de nosotros no lo conseguimos debido a nuestras ajetreadas vidas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/\" \/>\n<meta property=\"og:site_name\" content=\"AICA Orthopedics\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-14T08:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-26T07:31:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/How-to-Relieve-Lower-Back-Pain-When-Sleeping.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aicaos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"aicaos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/como-aliviar-el-dolor-lumbar-al-dormir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/como-aliviar-el-dolor-lumbar-al-dormir\\\/\"},\"author\":{\"name\":\"aicaos\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#\\\/schema\\\/person\\\/d68d1233a139d55e37d8e4d867f6dc24\"},\"headline\":\"C\u00f3mo aliviar el dolor lumbar al dormir\",\"datePublished\":\"2020-08-14T08:00:43+00:00\",\"dateModified\":\"2025-04-26T07:31:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/como-aliviar-el-dolor-lumbar-al-dormir\\\/\"},\"wordCount\":980,\"image\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/como-aliviar-el-dolor-lumbar-al-dormir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aica.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/How-to-Relieve-Lower-Back-Pain-When-Sleeping.jpg\",\"keywords\":[\"dolor lumbar\"],\"articleSection\":[\"Recuperaci\u00f3n de accidentes\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/como-aliviar-el-dolor-lumbar-al-dormir\\\/\",\"url\":\"https:\\\/\\\/aica.com\\\/es\\\/como-aliviar-el-dolor-lumbar-al-dormir\\\/\",\"name\":\"C\u00f3mo aliviar el dolor lumbar al dormir - AICA Orthopedics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/como-aliviar-el-dolor-lumbar-al-dormir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/como-aliviar-el-dolor-lumbar-al-dormir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aica.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/How-to-Relieve-Lower-Back-Pain-When-Sleeping.jpg\",\"datePublished\":\"2020-08-14T08:00:43+00:00\",\"dateModified\":\"2025-04-26T07:31:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#\\\/schema\\\/person\\\/d68d1233a139d55e37d8e4d867f6dc24\"},\"description\":\"Todos sabemos lo importante que es el sue\u00f1o de calidad para nuestra salud y, por desgracia, muchos de nosotros no lo conseguimos debido a nuestras ajetreadas vidas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/como-aliviar-el-dolor-lumbar-al-dormir\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aica.com\\\/es\\\/como-aliviar-el-dolor-lumbar-al-dormir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/como-aliviar-el-dolor-lumbar-al-dormir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aica.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/How-to-Relieve-Lower-Back-Pain-When-Sleeping.jpg\",\"contentUrl\":\"https:\\\/\\\/aica.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/How-to-Relieve-Lower-Back-Pain-When-Sleeping.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/como-aliviar-el-dolor-lumbar-al-dormir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/aica.com\\\/es\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo aliviar el dolor lumbar al dormir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/aica.com\\\/es\\\/\",\"name\":\"AICA Orthopedics\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aica.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aica.com\\\/es\\\/#\\\/schema\\\/person\\\/d68d1233a139d55e37d8e4d867f6dc24\",\"name\":\"aicaos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g\",\"caption\":\"aicaos\"},\"url\":\"https:\\\/\\\/aica.com\\\/es\\\/author\\\/aicaos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo aliviar el dolor lumbar al dormir - AICA Orthopedics","description":"Todos sabemos lo importante que es el sue\u00f1o de calidad para nuestra salud y, por desgracia, muchos de nosotros no lo conseguimos debido a nuestras ajetreadas vidas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo aliviar el dolor lumbar al dormir - AICA Orthopedics","og_description":"Todos sabemos lo importante que es el sue\u00f1o de calidad para nuestra salud y, por desgracia, muchos de nosotros no lo conseguimos debido a nuestras ajetreadas vidas.","og_url":"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/","og_site_name":"AICA Orthopedics","article_published_time":"2020-08-14T08:00:43+00:00","article_modified_time":"2025-04-26T07:31:32+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/How-to-Relieve-Lower-Back-Pain-When-Sleeping.jpg","type":"image\/jpeg"}],"author":"aicaos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"aicaos","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/#article","isPartOf":{"@id":"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/"},"author":{"name":"aicaos","@id":"https:\/\/aica.com\/es\/#\/schema\/person\/d68d1233a139d55e37d8e4d867f6dc24"},"headline":"C\u00f3mo aliviar el dolor lumbar al dormir","datePublished":"2020-08-14T08:00:43+00:00","dateModified":"2025-04-26T07:31:32+00:00","mainEntityOfPage":{"@id":"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/"},"wordCount":980,"image":{"@id":"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/#primaryimage"},"thumbnailUrl":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/How-to-Relieve-Lower-Back-Pain-When-Sleeping.jpg","keywords":["dolor lumbar"],"articleSection":["Recuperaci\u00f3n de accidentes"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/","url":"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/","name":"C\u00f3mo aliviar el dolor lumbar al dormir - AICA Orthopedics","isPartOf":{"@id":"https:\/\/aica.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/#primaryimage"},"image":{"@id":"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/#primaryimage"},"thumbnailUrl":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/How-to-Relieve-Lower-Back-Pain-When-Sleeping.jpg","datePublished":"2020-08-14T08:00:43+00:00","dateModified":"2025-04-26T07:31:32+00:00","author":{"@id":"https:\/\/aica.com\/es\/#\/schema\/person\/d68d1233a139d55e37d8e4d867f6dc24"},"description":"Todos sabemos lo importante que es el sue\u00f1o de calidad para nuestra salud y, por desgracia, muchos de nosotros no lo conseguimos debido a nuestras ajetreadas vidas.","breadcrumb":{"@id":"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/#primaryimage","url":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/How-to-Relieve-Lower-Back-Pain-When-Sleeping.jpg","contentUrl":"https:\/\/aica.com\/wp-content\/uploads\/2024\/09\/How-to-Relieve-Lower-Back-Pain-When-Sleeping.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/aica.com\/es\/como-aliviar-el-dolor-lumbar-al-dormir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/aica.com\/es\/homepage\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo aliviar el dolor lumbar al dormir"}]},{"@type":"WebSite","@id":"https:\/\/aica.com\/es\/#website","url":"https:\/\/aica.com\/es\/","name":"AICA Orthopedics","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aica.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/aica.com\/es\/#\/schema\/person\/d68d1233a139d55e37d8e4d867f6dc24","name":"aicaos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d10a6c78c65fe9f7a19da6de7c2db3dfb9bab4e578f7457014277d19257ecaa?s=96&d=mm&r=g","caption":"aicaos"},"url":"https:\/\/aica.com\/es\/author\/aicaos\/"}]}},"_links":{"self":[{"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/posts\/10011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/comments?post=10011"}],"version-history":[{"count":0,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/posts\/10011\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/media\/7588"}],"wp:attachment":[{"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/media?parent=10011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/categories?post=10011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aica.com\/es\/wp-json\/wp\/v2\/tags?post=10011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}